{"id":12123,"date":"2022-04-08T09:34:50","date_gmt":"2022-04-08T07:34:50","guid":{"rendered":"https:\/\/insieme.ch\/?p=12123"},"modified":"2022-04-08T18:10:38","modified_gmt":"2022-04-08T16:10:38","slug":"des-etats-generaux-de-linclusion-a-neuchatel","status":"publish","type":"post","link":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/","title":{"rendered":"Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel"},"content":{"rendered":"<p><!-- flzn:zn_pagebanner --><\/p>\n<header id=\"flzn-pagebanner-1\" class=\"zone zn-pagebanner with-bg bg-color\"><span class=\"zone-bg bg-color bgc-yellow-light alignfull\"><\/span><\/p>\n<div class=\"zone-block zn-pagebanner-block alignwide va-center\"><\/div>\n<\/header>\n<p><!-- \/flzn:zn_pagebanner --><br \/>\n<!-- flzn:zn_intro --><\/p>\n<div id=\"flzn-intro-1\" class=\"zone zn-intro with-bg bg-color\"><span class=\"zone-bg bg-color bgc-white alignfull\"><\/span><\/p>\n<div class=\"zone-block zn-intro-block alignsimple va-top\">\n<div class=\"addthis_inline_share_toolbox\"><\/div>\n<div class=\"row mw-content-zone  \">\n<div class=\"columns large-12\">\n<div class=\"row large-up-1 with-nice-alignment nbloc-1\">\n<div class=\"column zn-intro-col\">\n<div class=\"column-inner\">\n<div class=\"wig-content mw-content\">\n<p><strong>Afin de trouver des pistes pour mettre en \u0153uvre la nouvelle Loi sur l\u2019inclusion et l\u2019accompagnement des personnes vivant avec un handicap (LInCA), le Canton de Neuch\u00e2tel a organis\u00e9 des Etats g\u00e9n\u00e9raux de l\u2019inclusion le 1<sup>er<\/sup> avril dernier. insieme Neuch\u00e2tel a particip\u00e9 \u00e0 la journ\u00e9e en tant qu\u2019organisation de proches de personnes en situation de handicap.<\/strong><!--more--><\/p>\n<p>Le Canton de Neuch\u00e2tel a organis\u00e9 des Etats g\u00e9n\u00e9raux de l\u2019inclusion le 1<sup>er<\/sup> avril dernier. Le but de cette journ\u00e9e&#160;? Rassembler les parties prenantes pour discuter de th\u00e8mes tels que l\u2019inclusion professionnelle, l\u2019autod\u00e9termination dans le logement ou l\u2019exclusion sociale. \u00a0Il s\u2019agissait de susciter des pistes de r\u00e9flexion pour la mise en \u0153uvre de la nouvelle Loi sur l\u2019inclusion et l\u2019accompagnement des personnes vivant avec un handicap (LInCA). Les participant\u00b7e\u00b7s ont \u00e9galement pu faire la connaissance de Nathalie Christen, qui vient d\u2019\u00eatre nomm\u00e9e au nouvellement cr\u00e9\u00e9 poste de pr\u00e9pos\u00e9\u00b7e \u00e0 l\u2019inclusion.<\/p>\n<div id=\"attachment_12129\" class=\"wp-caption alignnone\" style=\"width:100%;max-width:1024px\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-12129 size-large\" src=\"https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin-1024x768.jpg\" alt=\"De nombreuses personnes de dos r\u00e9unies dans une salle \u00e9coutent une intervenante.\" width=\"1024\" height=\"768\" srcset=\"https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin-1024x768.jpg 1024w, https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin-300x225.jpg 300w, https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin-768x576.jpg 768w, https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin-1536x1152.jpg 1536w, https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin-320x240.jpg 320w, https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin-800x600.jpg 800w, https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin-1920x1440.jpg 1920w, https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p class=\"wp-caption-text\">Des Etats g\u00e9n\u00e9raux sur la th\u00e9matique de l&#8217;inclusion ont r\u00e9uni \u00e0 Neuch\u00e2tel de nombreuses personnes impliqu\u00e9es pour celle-ci.<\/p>\n<\/div>\n<h2><strong>Revendications des proches aidant\u00b7e\u00b7s<\/strong><\/h2>\n<p>\u00ab&#160;Le fait d\u2019\u00eatre inclus dans l\u2019organisation de la journ\u00e9e et d\u2019\u00eatre reconnus comme interlocuteurs \u00a0par le Conseil d\u2019Etat sur ces questions est extr\u00eamement positif pour nous. Il s\u2019agit maintenant de surfer sur la vague cr\u00e9\u00e9e par cette nouvelle loi pour maintenir un dialogue avec les autorit\u00e9s et obtenir des am\u00e9liorations&#160;\u00bb, souligne Virginie Haussener, secr\u00e9taire g\u00e9n\u00e9rale d\u2019insieme Neuch\u00e2tel, organisation qui, \u00e0 cette occasion, a co-anim\u00e9 un atelier sur les proches aidant\u00b7e\u00b7s avec Pro Infirmis Jura-Neuch\u00e2tel<\/p>\n<p>Et le r\u00e9sultat de l\u2019atelier montre que ces am\u00e9liorations sont plus que n\u00e9cessaires. Parmi les constats de ses participant\u00b7e\u00b7s&#160;: le manque de vue d\u2019ensemble sur les prestations disponibles, mais aussi la m\u00e9connaissance du handicap au sein de la population. Les participant\u00b7e\u00b7s ont \u00e9galement soulign\u00e9 l\u2019importance des offres mises sur pied par les organisations de personnes en situation de handicap, qui permettent aux familles de souffler. La mauvaise prise en charge m\u00e9dicale des personnes en situation de handicap par le personnel de soin, qui m\u00e9conna\u00eet souvent leurs besoins, a \u00e9galement \u00e9t\u00e9 \u00e9voqu\u00e9e.<\/p>\n<h2><strong>Plus de reconnaissance et de soutien<\/strong><\/h2>\n<p>Les propositions d\u2019am\u00e9lioration faites au Conseil d\u2019Etat par les participant\u00b7e\u00b7s de l\u2019atelier sont sans \u00e9quivoques&#160;: une information claire et centralis\u00e9e de la part du canton sur les prestations auxquelles ont droit les proches aidant\u00b7e\u00b7s. De m\u00eame que sur les services auxquels s\u2019adresser en fonction de sa situation. Un soutien (financier) de la part du canton aux organisations proposant des prestations aux personnes en situation de handicap et \u00e0 leurs proches a \u00e9galement \u00e9t\u00e9 demand\u00e9. Les participant\u00b7e\u00b7s \u00a0ont \u00e9galement mentionn\u00e9 le souhait que le statut de proche aidant\u00b7e\u00b7s soit mieux reconnu. La cr\u00e9ation d\u2019un poste de pr\u00e9pos\u00e9\u00b7e \u00e0 l\u2019accueil des personnes en situation de handicap dans les h\u00f4pitaux vient compl\u00e9ter les pistes propos\u00e9es au Conseil d\u2019Etat.<\/p>\n<p>La mani\u00e8re dont les propositions des participant\u00b7e\u00b7s seront mises en \u0153uvre concr\u00e8tement par le Canton est encore ouverte. Tout comme les moyens allou\u00e9s \u00e0 la mise en \u0153uvre de la nouvelle loi, afin qu\u2019elle ne reste pas lettre morte.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/insieme.ch\/fr\/news\/inclusion\/neuchatel-va-de-lavant\/\">\u00a0\u00ab&#160;Neuch\u00e2tel va de l\u2019avant&#160;\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/insieme.ch\/fr\/news\/inclusion\/cdph-mauvaise-note-pour-la-suisse\/\">\u00ab&#160;CDPH&#160;: mauvaise note pour la Suisse&#160;\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/insieme.ch\/fr\/theme\/famille\/proches-aidant-e-s\/\" target=\"_blank\" rel=\"noopener\">Proches aidants sur insieme.ch\u00a0<\/a><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<\/div>\n<p><!-- \/flzn:zn_intro --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Afin de trouver des pistes pour mettre en \u0153uvre la nouvelle Loi sur l\u2019inclusion et l\u2019accompagnement des personnes vivant avec un handicap (LInCA), le Canton de Neuch\u00e2tel a organis\u00e9 des Etats g\u00e9n\u00e9raux de l\u2019inclusion. <\/p>\n","protected":false},"author":21,"featured_media":12129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[156,161],"tags":[],"class_list":["post-12123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inclusion","category-famille","wp-sticky"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel<\/title>\n<meta name=\"description\" content=\"Afin de trouver des pistes pour mettre en \u0153uvre la nouvelle Loi sur l\u2019inclusion et l\u2019accompagnement des personnes vivant avec un handicap (LInCA), le Canton de Neuch\u00e2tel a organis\u00e9 des Etats g\u00e9n\u00e9raux de l\u2019inclusion le 1er avril dernier. insieme Neuch\u00e2tel a particip\u00e9 \u00e0 la journ\u00e9e en tant qu\u2019organisation de proches de personnes en situation de handicap.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel\" \/>\n<meta property=\"og:description\" content=\"Afin de trouver des pistes pour mettre en \u0153uvre la nouvelle Loi sur l\u2019inclusion et l\u2019accompagnement des personnes vivant avec un handicap (LInCA), le Canton de Neuch\u00e2tel a organis\u00e9 des Etats g\u00e9n\u00e9raux de l\u2019inclusion le 1er avril dernier. insieme Neuch\u00e2tel a particip\u00e9 \u00e0 la journ\u00e9e en tant qu\u2019organisation de proches de personnes en situation de handicap.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/\" \/>\n<meta property=\"og:site_name\" content=\"insieme.ch\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-08T07:34:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-08T16:10:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Regula Sandi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Regula Sandi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/\"},\"author\":{\"name\":\"Regula Sandi\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#\\\/schema\\\/person\\\/b9fed87b37b185acd0dca81f2aa989d2\"},\"headline\":\"Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel\",\"datePublished\":\"2022-04-08T07:34:50+00:00\",\"dateModified\":\"2022-04-08T16:10:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/\"},\"wordCount\":616,\"publisher\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2022\\\/04\\\/etats-generaux_20220401_salle-matin.jpg\",\"articleSection\":[\"Inclusion\",\"Famille\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/\",\"url\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/\",\"name\":\"Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2022\\\/04\\\/etats-generaux_20220401_salle-matin.jpg\",\"datePublished\":\"2022-04-08T07:34:50+00:00\",\"dateModified\":\"2022-04-08T16:10:38+00:00\",\"description\":\"Afin de trouver des pistes pour mettre en \u0153uvre la nouvelle Loi sur l\u2019inclusion et l\u2019accompagnement des personnes vivant avec un handicap (LInCA), le Canton de Neuch\u00e2tel a organis\u00e9 des Etats g\u00e9n\u00e9raux de l\u2019inclusion le 1er avril dernier. insieme Neuch\u00e2tel a particip\u00e9 \u00e0 la journ\u00e9e en tant qu\u2019organisation de proches de personnes en situation de handicap.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2022\\\/04\\\/etats-generaux_20220401_salle-matin.jpg\",\"contentUrl\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2022\\\/04\\\/etats-generaux_20220401_salle-matin.jpg\",\"width\":2000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/des-etats-generaux-de-linclusion-a-neuchatel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inclusion\",\"item\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/inclusion\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/\",\"name\":\"insieme.ch\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#organization\",\"name\":\"insieme\",\"url\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2021\\\/03\\\/logo-insieme.jpg\",\"contentUrl\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2021\\\/03\\\/logo-insieme.jpg\",\"width\":250,\"height\":250,\"caption\":\"insieme\"},\"image\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#\\\/schema\\\/person\\\/b9fed87b37b185acd0dca81f2aa989d2\",\"name\":\"Regula Sandi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3a1a8be222507867b2acf4f2e5bf1c8abfdfccf15cabb6a889f171c9d55171?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3a1a8be222507867b2acf4f2e5bf1c8abfdfccf15cabb6a889f171c9d55171?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff3a1a8be222507867b2acf4f2e5bf1c8abfdfccf15cabb6a889f171c9d55171?s=96&d=mm&r=g\",\"caption\":\"Regula Sandi\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel","description":"Afin de trouver des pistes pour mettre en \u0153uvre la nouvelle Loi sur l\u2019inclusion et l\u2019accompagnement des personnes vivant avec un handicap (LInCA), le Canton de Neuch\u00e2tel a organis\u00e9 des Etats g\u00e9n\u00e9raux de l\u2019inclusion le 1er avril dernier. insieme Neuch\u00e2tel a particip\u00e9 \u00e0 la journ\u00e9e en tant qu\u2019organisation de proches de personnes en situation de handicap.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/","og_locale":"fr_FR","og_type":"article","og_title":"Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel","og_description":"Afin de trouver des pistes pour mettre en \u0153uvre la nouvelle Loi sur l\u2019inclusion et l\u2019accompagnement des personnes vivant avec un handicap (LInCA), le Canton de Neuch\u00e2tel a organis\u00e9 des Etats g\u00e9n\u00e9raux de l\u2019inclusion le 1er avril dernier. insieme Neuch\u00e2tel a particip\u00e9 \u00e0 la journ\u00e9e en tant qu\u2019organisation de proches de personnes en situation de handicap.","og_url":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/","og_site_name":"insieme.ch","article_published_time":"2022-04-08T07:34:50+00:00","article_modified_time":"2022-04-08T16:10:38+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin.jpg","type":"image\/jpeg"}],"author":"Regula Sandi","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Regula Sandi","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/#article","isPartOf":{"@id":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/"},"author":{"name":"Regula Sandi","@id":"https:\/\/insieme.ch\/fr\/#\/schema\/person\/b9fed87b37b185acd0dca81f2aa989d2"},"headline":"Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel","datePublished":"2022-04-08T07:34:50+00:00","dateModified":"2022-04-08T16:10:38+00:00","mainEntityOfPage":{"@id":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/"},"wordCount":616,"publisher":{"@id":"https:\/\/insieme.ch\/fr\/#organization"},"image":{"@id":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/#primaryimage"},"thumbnailUrl":"https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin.jpg","articleSection":["Inclusion","Famille"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/","url":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/","name":"Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel","isPartOf":{"@id":"https:\/\/insieme.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/#primaryimage"},"image":{"@id":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/#primaryimage"},"thumbnailUrl":"https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin.jpg","datePublished":"2022-04-08T07:34:50+00:00","dateModified":"2022-04-08T16:10:38+00:00","description":"Afin de trouver des pistes pour mettre en \u0153uvre la nouvelle Loi sur l\u2019inclusion et l\u2019accompagnement des personnes vivant avec un handicap (LInCA), le Canton de Neuch\u00e2tel a organis\u00e9 des Etats g\u00e9n\u00e9raux de l\u2019inclusion le 1er avril dernier. insieme Neuch\u00e2tel a particip\u00e9 \u00e0 la journ\u00e9e en tant qu\u2019organisation de proches de personnes en situation de handicap.","breadcrumb":{"@id":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/#primaryimage","url":"https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin.jpg","contentUrl":"https:\/\/insieme.ch\/wp-inside\/uploads\/2022\/04\/etats-generaux_20220401_salle-matin.jpg","width":2000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/insieme.ch\/fr\/news\/inclusion\/des-etats-generaux-de-linclusion-a-neuchatel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/insieme.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/insieme.ch\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Inclusion","item":"https:\/\/insieme.ch\/fr\/news\/inclusion\/"},{"@type":"ListItem","position":4,"name":"Des Etats g\u00e9n\u00e9raux de l\u2019inclusion \u00e0 Neuch\u00e2tel"}]},{"@type":"WebSite","@id":"https:\/\/insieme.ch\/fr\/#website","url":"https:\/\/insieme.ch\/fr\/","name":"insieme.ch","description":"","publisher":{"@id":"https:\/\/insieme.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/insieme.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/insieme.ch\/fr\/#organization","name":"insieme","url":"https:\/\/insieme.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/insieme.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/03\/logo-insieme.jpg","contentUrl":"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/03\/logo-insieme.jpg","width":250,"height":250,"caption":"insieme"},"image":{"@id":"https:\/\/insieme.ch\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/insieme.ch\/fr\/#\/schema\/person\/b9fed87b37b185acd0dca81f2aa989d2","name":"Regula Sandi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ff3a1a8be222507867b2acf4f2e5bf1c8abfdfccf15cabb6a889f171c9d55171?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff3a1a8be222507867b2acf4f2e5bf1c8abfdfccf15cabb6a889f171c9d55171?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff3a1a8be222507867b2acf4f2e5bf1c8abfdfccf15cabb6a889f171c9d55171?s=96&d=mm&r=g","caption":"Regula Sandi"}}]}},"_links":{"self":[{"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/posts\/12123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/comments?post=12123"}],"version-history":[{"count":5,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/posts\/12123\/revisions"}],"predecessor-version":[{"id":12150,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/posts\/12123\/revisions\/12150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/media\/12129"}],"wp:attachment":[{"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/media?parent=12123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/categories?post=12123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/tags?post=12123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}