{"id":11175,"date":"2021-12-16T14:29:55","date_gmt":"2021-12-16T13:29:55","guid":{"rendered":"https:\/\/insieme.ch\/?p=11175"},"modified":"2021-12-16T14:29:55","modified_gmt":"2021-12-16T13:29:55","slug":"des-statistiques-lacunaires","status":"publish","type":"post","link":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/","title":{"rendered":"Des statistiques lacunaires"},"content":{"rendered":"<p><!-- flzn:zn_pagebanner --><\/p>\n<header id=\"flzn-pagebanner-1\" class=\"zone zn-pagebanner with-bg bg-color\"><span class=\"zone-bg bg-color bgc-yellow-light alignfull\"><\/span><\/p>\n<div class=\"zone-block zn-pagebanner-block alignwide va-center\"><\/div>\n<\/header>\n<p><!-- \/flzn:zn_pagebanner --><br \/>\n<!-- flzn:zn_intro --><\/p>\n<div id=\"flzn-intro-1\" class=\"zone zn-intro with-bg bg-color\"><span class=\"zone-bg bg-color bgc-white alignfull\"><\/span><\/p>\n<div class=\"zone-block zn-intro-block alignsimple va-top\">\n<div class=\"addthis_inline_share_toolbox\"><\/div>\n<div class=\"row mw-content-zone  \">\n<div class=\"columns large-12\">\n<div class=\"row large-up-1 with-nice-alignment nbloc-1\">\n<div class=\"column zn-intro-col\">\n<div class=\"column-inner\">\n<div class=\"wig-content mw-content\">\n<p><strong>Les nouveaux \u00ab&#160;indicateurs de l\u2019\u00e9galit\u00e9 pour les personnes handicap\u00e9es&#160;\u00bb publi\u00e9s par l\u2019Office f\u00e9d\u00e9ral de la statistique (OFS) montrent qu\u2019il est essentiel de rendre les environnements de travail plus inclusifs. Ils sont \u00e9galement l\u2019occasion de constater le manque de donn\u00e9es sur la situation des personnes avec un handicap mental en Suisse.<\/strong><\/p>\n<p><!--more--><br \/>\nL\u2019Office f\u00e9d\u00e9ral de la statistique (OFS) a publi\u00e9 d\u00e9but d\u00e9cembre ses \u00ab&#160;indicateurs de l\u2019\u00e9galit\u00e9 pour les personnes handicap\u00e9es&#160;\u00bb. Selon ces r\u00e9sultats, les personnes en situation de handicap participent largement au march\u00e9 du travail. En 2019, c\u2019\u00e9tait le cas de 72&#160;% d\u2019entre elles. Ces chiffres ne refl\u00e8tent toutefois pas la situation de toutes les personnes vivant avec un handicap et en particulier de celles avec un handicap mental.<\/p>\n<p>D\u2019une part, les personnes qui travaillent sur le march\u00e9 secondaire du travail, par exemple en atelier prot\u00e9g\u00e9, ne sont pas exclues, mais extr\u00eamement peu repr\u00e9sent\u00e9es dans cette statistique. D\u2019autre part, la statistique publi\u00e9e par l\u2019OFS se base largement sur des enqu\u00eates g\u00e9n\u00e9rales de population \u00e0 l\u2019instar de l\u2019 \u00ab&#160;Enqu\u00eate sur les revenus et les conditions de vie&#160;\u00bb ou de l\u2019 \u00ab&#160;Enqu\u00eate Suisse sur la sant\u00e9&#160;\u00bb. Celles-ci sont men\u00e9es uniquement aupr\u00e8s de personnes r\u00e9sidant dans des m\u00e9nages priv\u00e9s et ne tiennent donc pas compte de celles vivant en institution.<\/p>\n<div id=\"attachment_11177\" class=\"wp-caption aligncenter\" style=\"width:100%;max-width:2000px\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-11177 size-full\" src=\"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus.jpg\" alt=\"Un homme effectue un travail avec un appareil de montage.\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus.jpg 2000w, https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus-300x200.jpg 300w, https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus-1024x682.jpg 1024w, https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus-768x512.jpg 768w, https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus-1536x1024.jpg 1536w, https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus-320x213.jpg 320w, https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus-800x533.jpg 800w, https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p class=\"wp-caption-text\">Le v\u00e9cu de nombreuses personnes en situation de handicap mental vivant ou travaillant en institution n\u2019est pas ou peu pris en compte dans la statistique de l&#8217;OFS. \u00a9 Vera Markus<\/p>\n<\/p>\n<\/div>\n<h2>Quid des personnes vivant en institution&#160;?<\/h2>\n<p>Les indicateurs publi\u00e9s par l\u2019OFS sur les contacts sociaux, la mobilit\u00e9, la formation, la participation au march\u00e9 du travail et la qualit\u00e9 de vie au travail ne refl\u00e8tent que la situation des personnes avec handicap qui vivent chez elles et, en grande majorit\u00e9, qui travaillent sur le march\u00e9 primaire. Le v\u00e9cu de nombreuses personnes en situation de handicap mental vivant ou travaillant en institution n\u2019est pas ou peu pris en compte dans cette statistique. Celle-ci porte pourtant sp\u00e9cifiquement sur l\u2019\u00e9galit\u00e9 pour les personnes en situation de handicap.<\/p>\n<h2>Un panorama statistique qui laisse \u00e0 d\u00e9sirer<\/h2>\n<p>Le manque de prise en compte du v\u00e9cu des personnes vivant en institution n\u2019est pas un probl\u00e8me isol\u00e9. De mani\u00e8re g\u00e9n\u00e9rale, les donn\u00e9es relatives au handicap laissent \u00e0 d\u00e9sirer. Les causes sont multiples&#160;: difficult\u00e9s de d\u00e9finition (qu\u2019est-ce que le handicap&#160;?), probl\u00e8mes statistiques, invisibilit\u00e9 du handicap dans les recherches sur d\u2019autres th\u00e8mes. Ces \u00e9l\u00e9ments cr\u00e9ent des difficult\u00e9s de taille lorsqu\u2019il s\u2019agit de d\u00e9terminer o\u00f9 se situent les probl\u00e8mes, de d\u00e9velopper des mesures cibl\u00e9es pour lutter contre les in\u00e9galit\u00e9s ou de prioriser les actions \u00e0 mener.<\/p>\n<p><a href=\"https:\/\/insieme.ch\/fr\/theme\/vie-professionnelle\/monde-professionnel\/\">Monde professionnel sur insieme.ch<\/a><br \/>\n<a href=\"https:\/\/www.bfs.admin.ch\/bfs\/fr\/home\/statistiques\/situation-economique-sociale-population\/enquetes\/silc.assetdetail.19464131.html\">Communiqu\u00e9 de presse de l\u2019OFS<\/a><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<\/div>\n<p><!-- \/flzn:zn_intro --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les donn\u00e9es de l&#8217;Office f\u00e9d\u00e9ral de la statistique ne refl\u00e8tent pas la situation des personnes vivant avec une d\u00e9ficience intellectuelle.<\/p>\n","protected":false},"author":3,"featured_media":11177,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[157,159],"tags":[],"class_list":["post-11175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logement","category-vie-professionnelle","wp-sticky"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Des statistiques lacunaires<\/title>\n<meta name=\"description\" content=\"Les nouveaux \u00abindicateurs de l\u2019\u00e9galit\u00e9 pour les personnes handicap\u00e9es\u00bb de l&#039;OFS ne refl\u00e8tent pas la situation des personnes vivant avec une d\u00e9ficience intellectuelle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des statistiques lacunaires\" \/>\n<meta property=\"og:description\" content=\"Les nouveaux \u00abindicateurs de l\u2019\u00e9galit\u00e9 pour les personnes handicap\u00e9es\u00bb de l&#039;OFS ne refl\u00e8tent pas la situation des personnes vivant avec une d\u00e9ficience intellectuelle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/\" \/>\n<meta property=\"og:site_name\" content=\"insieme.ch\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-16T13:29:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lise Tran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lise Tran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/\"},\"author\":{\"name\":\"Lise Tran\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#\\\/schema\\\/person\\\/48d0d97cbe408d1edf6d5c70bae925fa\"},\"headline\":\"Des statistiques lacunaires\",\"datePublished\":\"2021-12-16T13:29:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/\"},\"wordCount\":501,\"publisher\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2021\\\/12\\\/foto-arbeit_vera-markus.jpg\",\"articleSection\":[\"Logement\",\"Vie professionnelle\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/\",\"url\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/\",\"name\":\"Des statistiques lacunaires\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2021\\\/12\\\/foto-arbeit_vera-markus.jpg\",\"datePublished\":\"2021-12-16T13:29:55+00:00\",\"description\":\"Les nouveaux \u00abindicateurs de l\u2019\u00e9galit\u00e9 pour les personnes handicap\u00e9es\u00bb de l'OFS ne refl\u00e8tent pas la situation des personnes vivant avec une d\u00e9ficience intellectuelle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2021\\\/12\\\/foto-arbeit_vera-markus.jpg\",\"contentUrl\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2021\\\/12\\\/foto-arbeit_vera-markus.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"Montagearbeit in der Stiftung Braendi in Kriens \\\/ Luzern Februar 2015 Bild: \u00a9 Vera Markus v.markus@bluewin.ch www.veramarkus.com *** Local Caption *** Christian Stettler 041 440 52 93 079 471 24 71 h_stettler@bluewin.ch (Vater) Stiftung Braendi Horwerstrasse 123 6011 Kriens Tel. 041 349 02 02 Fax 041 349 02 12 stiftung@braendi.ch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/des-statistiques-lacunaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vie professionnelle\",\"item\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/news\\\/vie-professionnelle\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Des statistiques lacunaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/\",\"name\":\"insieme.ch\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#organization\",\"name\":\"insieme\",\"url\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2021\\\/03\\\/logo-insieme.jpg\",\"contentUrl\":\"https:\\\/\\\/insieme.ch\\\/wp-inside\\\/uploads\\\/2021\\\/03\\\/logo-insieme.jpg\",\"width\":250,\"height\":250,\"caption\":\"insieme\"},\"image\":{\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/insieme.ch\\\/fr\\\/#\\\/schema\\\/person\\\/48d0d97cbe408d1edf6d5c70bae925fa\",\"name\":\"Lise Tran\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1028ac8c35a45d0420275ec991fe6d9964020c33f7db80209f71a09cbfc3a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1028ac8c35a45d0420275ec991fe6d9964020c33f7db80209f71a09cbfc3a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c1028ac8c35a45d0420275ec991fe6d9964020c33f7db80209f71a09cbfc3a8?s=96&d=mm&r=g\",\"caption\":\"Lise Tran\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Des statistiques lacunaires","description":"Les nouveaux \u00abindicateurs de l\u2019\u00e9galit\u00e9 pour les personnes handicap\u00e9es\u00bb de l'OFS ne refl\u00e8tent pas la situation des personnes vivant avec une d\u00e9ficience intellectuelle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Des statistiques lacunaires","og_description":"Les nouveaux \u00abindicateurs de l\u2019\u00e9galit\u00e9 pour les personnes handicap\u00e9es\u00bb de l'OFS ne refl\u00e8tent pas la situation des personnes vivant avec une d\u00e9ficience intellectuelle.","og_url":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/","og_site_name":"insieme.ch","article_published_time":"2021-12-16T13:29:55+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus.jpg","type":"image\/jpeg"}],"author":"Lise Tran","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lise Tran","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/#article","isPartOf":{"@id":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/"},"author":{"name":"Lise Tran","@id":"https:\/\/insieme.ch\/fr\/#\/schema\/person\/48d0d97cbe408d1edf6d5c70bae925fa"},"headline":"Des statistiques lacunaires","datePublished":"2021-12-16T13:29:55+00:00","mainEntityOfPage":{"@id":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/"},"wordCount":501,"publisher":{"@id":"https:\/\/insieme.ch\/fr\/#organization"},"image":{"@id":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/#primaryimage"},"thumbnailUrl":"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus.jpg","articleSection":["Logement","Vie professionnelle"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/","url":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/","name":"Des statistiques lacunaires","isPartOf":{"@id":"https:\/\/insieme.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/#primaryimage"},"image":{"@id":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/#primaryimage"},"thumbnailUrl":"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus.jpg","datePublished":"2021-12-16T13:29:55+00:00","description":"Les nouveaux \u00abindicateurs de l\u2019\u00e9galit\u00e9 pour les personnes handicap\u00e9es\u00bb de l'OFS ne refl\u00e8tent pas la situation des personnes vivant avec une d\u00e9ficience intellectuelle.","breadcrumb":{"@id":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/#primaryimage","url":"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus.jpg","contentUrl":"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/12\/foto-arbeit_vera-markus.jpg","width":2000,"height":1333,"caption":"Montagearbeit in der Stiftung Braendi in Kriens \/ Luzern Februar 2015 Bild: \u00a9 Vera Markus v.markus@bluewin.ch www.veramarkus.com *** Local Caption *** Christian Stettler 041 440 52 93 079 471 24 71 h_stettler@bluewin.ch (Vater) Stiftung Braendi Horwerstrasse 123 6011 Kriens Tel. 041 349 02 02 Fax 041 349 02 12 stiftung@braendi.ch"},{"@type":"BreadcrumbList","@id":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/des-statistiques-lacunaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/insieme.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/insieme.ch\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Vie professionnelle","item":"https:\/\/insieme.ch\/fr\/news\/vie-professionnelle\/"},{"@type":"ListItem","position":4,"name":"Des statistiques lacunaires"}]},{"@type":"WebSite","@id":"https:\/\/insieme.ch\/fr\/#website","url":"https:\/\/insieme.ch\/fr\/","name":"insieme.ch","description":"","publisher":{"@id":"https:\/\/insieme.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/insieme.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/insieme.ch\/fr\/#organization","name":"insieme","url":"https:\/\/insieme.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/insieme.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/03\/logo-insieme.jpg","contentUrl":"https:\/\/insieme.ch\/wp-inside\/uploads\/2021\/03\/logo-insieme.jpg","width":250,"height":250,"caption":"insieme"},"image":{"@id":"https:\/\/insieme.ch\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/insieme.ch\/fr\/#\/schema\/person\/48d0d97cbe408d1edf6d5c70bae925fa","name":"Lise Tran","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c1028ac8c35a45d0420275ec991fe6d9964020c33f7db80209f71a09cbfc3a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c1028ac8c35a45d0420275ec991fe6d9964020c33f7db80209f71a09cbfc3a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c1028ac8c35a45d0420275ec991fe6d9964020c33f7db80209f71a09cbfc3a8?s=96&d=mm&r=g","caption":"Lise Tran"}}]}},"_links":{"self":[{"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/posts\/11175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/comments?post=11175"}],"version-history":[{"count":2,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/posts\/11175\/revisions"}],"predecessor-version":[{"id":11179,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/posts\/11175\/revisions\/11179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/media\/11177"}],"wp:attachment":[{"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/media?parent=11175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/categories?post=11175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insieme.ch\/fr\/wp-json\/wp\/v2\/tags?post=11175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}